{"id":56,"date":"2013-02-27T11:29:31","date_gmt":"2013-02-27T10:29:31","guid":{"rendered":"http:\/\/www.informatic-a.it\/wordpress\/?p=56"},"modified":"2013-05-20T18:16:38","modified_gmt":"2013-05-20T16:16:38","slug":"corso-informatica-di-base-a-treviso","status":"publish","type":"post","link":"https:\/\/www.informatic-a.it\/wordpress\/corso-informatica\/corso-informatica-di-base-a-treviso.html","title":{"rendered":"Corso Informatica di Base a Treviso"},"content":{"rendered":"<p><span style=\"font-size: large; color: #3366ff;\"><strong><a href=\"http:\/\/www.informatic-a.it\/wordpress\/wp-content\/uploads\/2013\/02\/computer_colori.jpg\"><img loading=\"lazy\" class=\"alignleft  wp-image-58\" title=\"computer_colori\" src=\"http:\/\/www.informatic-a.it\/wordpress\/wp-content\/uploads\/2013\/02\/computer_colori.jpg\" alt=\"\" width=\"301\" height=\"274\" srcset=\"https:\/\/www.informatic-a.it\/wordpress\/wp-content\/uploads\/2013\/02\/computer_colori.jpg 376w, https:\/\/www.informatic-a.it\/wordpress\/wp-content\/uploads\/2013\/02\/computer_colori-300x273.jpg 300w\" sizes=\"(max-width: 301px) 100vw, 301px\" \/><\/a>INFORMATICA DI BASE PER ADULTI a Treviso.<\/strong><strong><br \/>\n<\/strong><\/span><strong><br \/>\n<\/strong><strong>Corso tenuto da Roberto Sorbara<\/strong><\/p>\n<p>Questo <strong>corso di informatica di base \u00e8 rivolto a persone adulte<\/strong> che hanno bisogno di avvicinarsi all\u2019utilizzo del computer e impadronirsi delle tecnologie informatiche di base.<\/p>\n<p>Il corso tratta gli argomenti principali dell\u2019utilizzo del computer, tutte quelle cose che si fanno quotidianamente, consultare la posta elettronica, consultare internet,\u2026<\/p>\n<p><strong>Verranno spiegati :<\/strong><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Il funzionamento del computer<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Il sistema operativo<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le principali periferiche<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le cartelle e la loro gestione<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La gestione dei files<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La posta elettronica<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Internet e la navigazione sul WEB<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 I programmi di videoscrittura<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 I social network, Facebook,\u2026<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Skype, MSN, \u2026<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La masterizzazione<br \/>\n&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le Foto e le Immagini<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>INFORMAZIONI \/ SEGRETERIA<\/strong><\/span><br \/>\n<strong>Per informazioni e iscrizioni al CORSO DI WEBDESIGN:<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>docente Roberto Sorbara:<\/strong><\/span><br \/>\ncell: 328 3658672<br \/>\ne-mail : <a href=\"mailto:info@informatic-a.it\">info@informatic-a.it<\/a><\/p>\n<p><strong>o <a href=\"http:\/\/www.informatic-a.it\/wordpress\/contatti\">CLICCA QUI<\/a><\/strong><a href=\"http:\/\/www.informatic-a.it\/wordpress\/contatti\"> <strong>sui CONTATTI<\/strong><\/a><\/p>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f81-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wordpress\/wp-json\/wp\/v2\/posts\/56#wpcf7-f81-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"81\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.3.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f81-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p>Il tuo nome (richiesto)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>La tua email (richiesto)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Oggetto<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Il tuo messaggio<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/p>\n<p><input type=\"submit\" value=\"Invia\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"<p>INFORMATICA DI BASE PER ADULTI a Treviso. Corso tenuto da Roberto Sorbara Questo corso di informatica di base \u00e8 rivolto a persone adulte che hanno bisogno di avvicinarsi all\u2019utilizzo del computer e impadronirsi delle tecnologie informatiche di base. Il corso tratta gli argomenti principali dell\u2019utilizzo del computer, tutte quelle cose che si fanno quotidianamente, consultare&hellip;<\/p>\n","protected":false},"author":1,"featured_media":58,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,27],"tags":[29,33,31,28,32,30,36,35,37,34,13],"_links":{"self":[{"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/posts\/56"}],"collection":[{"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":8,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/posts\/56\/revisions"}],"predecessor-version":[{"id":107,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/posts\/56\/revisions\/107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/media\/58"}],"wp:attachment":[{"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/media?parent=56"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/categories?post=56"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/tags?post=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}