{"id":274,"date":"2020-01-12T15:08:45","date_gmt":"2020-01-12T14:08:45","guid":{"rendered":"http:\/\/www.informatic-a.it\/wordpress\/?p=274"},"modified":"2020-01-12T15:08:45","modified_gmt":"2020-01-12T14:08:45","slug":"corso-informatica-treviso-adulti-e-anziani","status":"publish","type":"post","link":"https:\/\/www.informatic-a.it\/wordpress\/corso-informatica\/corso-informatica-treviso-adulti-e-anziani.html","title":{"rendered":"Corso Informatica Treviso &#8211; Adulti e Anziani"},"content":{"rendered":"\n<p>Corso di Informatica a Treviso &#8211; Per Adulti e Anziani<\/p>\n\n\n\n<p>Corso Base per imparare le Nozioni di Base del Computer e Suo Utilizzo<\/p>\n\n\n\n<p>Navigazione Web, Social, Skype, Gestione Foto, creare cartelle, Word e Office<\/p>\n\n\n\n<p>Per chi parte da Zero ed \u00e8 alle Prime Armi<\/p>\n\n\n\n<p>Da Mercoled\u00ec 22 Gennaio ore 20 alle 22 per 6 Mercoled\u00ec<\/p>\n\n\n\n<p>Per chi vuole si possono fare Corsi a Domicilio individuali con Orari eGiorni flessibili da concordare<\/p>\n\n\n\n<p>Per informazioni e Costi: Roberto 3283658672 info@robertosorbara.com<\/p>\n\n\n\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f81-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wordpress\/wp-json\/wp\/v2\/posts\/274#wpcf7-f81-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"81\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.3.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f81-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p>Il tuo nome (richiesto)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>La tua email (richiesto)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Oggetto<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Il tuo messaggio<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/p>\n<p><input type=\"submit\" value=\"Invia\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Corso di Informatica a Treviso &#8211; Per Adulti e Anziani Corso Base per imparare le Nozioni di Base del Computer e Suo Utilizzo Navigazione Web, Social, Skype, Gestione Foto, creare cartelle, Word e Office Per chi parte da Zero ed \u00e8 alle Prime Armi Da Mercoled\u00ec 22 Gennaio ore 20 alle 22 per 6 Mercoled\u00ec&hellip;<\/p>\n","protected":false},"author":1,"featured_media":275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[59,1,27],"tags":[28,93,94,30],"_links":{"self":[{"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/posts\/274"}],"collection":[{"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/comments?post=274"}],"version-history":[{"count":1,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/posts\/274\/revisions"}],"predecessor-version":[{"id":276,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/posts\/274\/revisions\/276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/media\/275"}],"wp:attachment":[{"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/media?parent=274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/categories?post=274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.informatic-a.it\/wordpress\/wp-json\/wp\/v2\/tags?post=274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}